{"id":157,"date":"2022-02-14T16:10:49","date_gmt":"2022-02-14T15:10:49","guid":{"rendered":"https:\/\/coach-d-azur.com\/?page_id=157"},"modified":"2022-03-10T14:27:38","modified_gmt":"2022-03-10T13:27:38","slug":"les-courbatures","status":"publish","type":"page","link":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/","title":{"rendered":"Les courbatures"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"157\" class=\"elementor elementor-157\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a572f7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a572f7c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61be3bf6\" data-id=\"61be3bf6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db93617 elementor-widget elementor-widget-image\" data-id=\"4db93617\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"435\" height=\"210\" src=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png 435w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02-300x145.png 300w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" style=\"width:100%;height:48.28%;max-width:435px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-466bbe34\" data-id=\"466bbe34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-538ea949 hfe-nav-menu__align-right hfe-nav-menu__theme-icon-yes hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child hfe-nav-menu__breakpoint-tablet elementor-widget elementor-widget-navigation-menu\" data-id=\"538ea949\" data-element_type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:11,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;width_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;220&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__none\" data-layout=\"horizontal\">\n\t\t\t\t<div class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" tabindex=\"0\" class=\"fas fa-align-justify\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;fas fa-align-justify&quot;&gt;&lt;\/i&gt;\" data-close-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;far fa-window-close&quot;&gt;&lt;\/i&gt;\" data-full-width=\"yes\"><ul id=\"menu-1-538ea949\" class=\"hfe-nav-menu\"><li id=\"menu-item-140\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/le-centre\/\" class = \"hfe-menu-item\">Le centre de soins<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Ouvrir le menu<\/span><\/button>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-1018\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/la-kinesitherapie\/\" class = \"hfe-sub-menu-item\">La Kin\u00e9sith\u00e9rapie<\/a><\/li>\n\t<li id=\"menu-item-178\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-massages\/\" class = \"hfe-sub-menu-item\">Les massages<\/a><\/li>\n\t<li id=\"menu-item-176\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-dispositifs-medicaux\/\" class = \"hfe-sub-menu-item\">Les dispositifs m\u00e9dicaux<\/a><\/li>\n\t<li id=\"menu-item-417\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-ondes-de-choc\/\" class = \"hfe-sub-menu-item\">Les ondes de choc<\/a><\/li>\n\t<li id=\"menu-item-182\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/soin-esthetique\/\" class = \"hfe-sub-menu-item\">Les soins esth\u00e9tiques<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-141\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/conseils\/\" class = \"hfe-menu-item\">Conseils<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Ouvrir le menu<\/span><\/button>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-171\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/exercice-physique\/\" class = \"hfe-sub-menu-item\">Exercices physiques<span class='hfe-menu-toggle sub-arrow hfe-menu-child-1'><i class='fa'><\/i><\/span><\/a><\/div>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-523\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/un-ventre-plat\/\" class = \"hfe-sub-menu-item\">Un ventre plat<\/a><\/li>\n\t\t<li id=\"menu-item-473\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/le-cardio-training\/\" class = \"hfe-sub-menu-item\">Le cardio training<\/a><\/li>\n\t\t<li id=\"menu-item-472\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/la-course-a-pied\/\" class = \"hfe-sub-menu-item\">La course \u00e0 pied<\/a><\/li>\n\t\t<li id=\"menu-item-499\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-etirements\/\" class = \"hfe-sub-menu-item\">Les \u00e9tirements<\/a><\/li>\n\t\t<li id=\"menu-item-470\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-abdominaux\/\" class = \"hfe-sub-menu-item\">Les abdominaux<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-172\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/lalimentation\/\" class = \"hfe-sub-menu-item\">L\u2019alimentation<\/a><\/li>\n\t<li id=\"menu-item-177\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-entorses\/\" class = \"hfe-sub-menu-item\">Les entorses<\/a><\/li>\n\t<li id=\"menu-item-179\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-tendinites\/\" class = \"hfe-sub-menu-item\">Les tendinites<\/a><\/li>\n\t<li id=\"menu-item-173\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/larthrose\/\" class = \"hfe-sub-menu-item\">L\u2019arthrose<\/a><\/li>\n\t<li id=\"menu-item-174\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/le-mal-de-dos\/\" class = \"hfe-sub-menu-item\">Le mal de dos<\/a><\/li>\n\t<li id=\"menu-item-180\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/maigrir\/\" class = \"hfe-sub-menu-item\">Maigrir<\/a><\/li>\n\t<li id=\"menu-item-175\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/\" class = \"hfe-sub-menu-item\">Les courbatures<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-143\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/videos\/\" class = \"hfe-menu-item\">Arts<\/a><\/li>\n<li id=\"menu-item-181\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/meditation\/\" class = \"hfe-menu-item\">M\u00e9ditation<\/a><\/li>\n<li id=\"menu-item-144\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/coach-d-azur.com\/index.php\/contact\/\" class = \"hfe-menu-item\">Contact<\/a><\/li>\n<\/ul><\/nav>              \n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-398befb5 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"398befb5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-539a19b2\" data-id=\"539a19b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-268694d5 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"268694d5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Conseils<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28653d3e animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"28653d3e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Les courbatures<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1427590e animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1427590e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Les\u00a0courbatures\u00a0sont des\u00a0douleurs musculaires sans gravit\u00e9, cons\u00e9cutives \u00e0 un effort important ou suite a une infection\u00a0virale\u00a0(comme lors d&rsquo;un\u00a0syndrome grippal).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-efe3131\" data-id=\"efe3131\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a4d660f animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5a4d660f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1400}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"724\" src=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter-2-1024x988.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter-2-1024x988.jpg 1024w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter-2-300x290.jpg 300w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter-2-768x741.jpg 768w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter-2.jpg 1061w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" style=\"width:100%;height:96.51%;max-width:1061px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7877aa04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7877aa04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-43d3fa1b\" data-id=\"43d3fa1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67d801bf animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"67d801bf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter.jpg 681w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/courbature-comment-les-eviter-200x300.jpg 200w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" style=\"width:100%;height:150.37%;max-width:681px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28c7f23d\" data-id=\"28c7f23d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52395181 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"52395181\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Elles sont les plus douloureuses 12 \u00e0 48 heures apr\u00e8s l&rsquo;effort et durent g\u00e9n\u00e9ralement 5 \u00e0 7 jours<sup>\u00a0<\/sup>.<\/p><p>La dur\u00e9e et l&rsquo;intensit\u00e9 des courbatures varient en fonction de l&rsquo;effort produit et de la condition physique de la personne et son habitude \u00e0 un type d&rsquo;effort ou mouvement particulier.<\/p><p>\u00a0<\/p><p>Les\u00a0courbatures\u00a0 apparaissent lorsqu&rsquo;un muscle n&rsquo;est pas habitu\u00e9 \u00e0 un exercice, \u00e0 une charge d\u2019effort importante, ou a subi principalement des contractions musculaires de type excentrique (r\u00e9ception d\u2019appui lors des foul\u00e9es de jogging par exemple).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d846203 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d846203\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5e38fb\" data-id=\"c5e38fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55496412 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55496412\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-72deae2d\" data-id=\"72deae2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76157128 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"76157128\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" id=\"m_-5519691688193684477Image_x0020_9\" class=\"CToWUd alignleft\" src=\"https:\/\/mail.google.com\/mail\/u\/0?ui=2&amp;ik=a22552e2ee&amp;attid=0.28&amp;permmsgid=msg-f:1723455332488256890&amp;th=17eaf17e5f371d7a&amp;view=fimg&amp;fur=ip&amp;sz=s0-l75-ft&amp;attbid=ANGjdJ_hkqsx0l_0dE6nnWKxaAWmLZK5WJi09yHSTYDltB6l-L0rQ0q38eshNdtZrhwmoiMkHpX6LrQYrLdp1lAYnZbB767UIaqUYxH7zIIQwH9gnyCM6lwd94kAZ6s&amp;disp=emb\" width=\"222\" height=\"167\" border=\"0\" data-image-whitelisted=\"\" \/><\/p><p>Elles sont dues \u00e0 de petits \u00e9panchements de sang provoqu\u00e9s par rupture des capillaires sanguins et des micro-traumatismes au niveau\u00a0des cellules musculaires<sup>\u00a0<\/sup>.<\/p><p>L&rsquo;acide lactique n&rsquo;est pas responsable des courbatures, contrairement \u00e0 ce qui est souvent expliqu\u00e9.<\/p><p>\u00a0<\/p><p><strong><u>Conseils pour \u00e9viter ou r\u00e9duire les effets des courbatures\u00a0:<\/u><\/strong><\/p><ul><li>Ne pas entreprendre de comp\u00e9tition ou d\u2019entra\u00eenement intensif \u00ab \u00e0 contre c\u0153ur \u00bb, si vous n\u2019\u00eates pas motiv\u00e9 et enthousiaste (le sport doit toujours rester un plaisir et non une contrainte, m\u00eame si il faut parfois un petit effort pour se stimuler \u2026)<\/li><li>Eviter le travail musculaire en <strong>contraction excentrique\u00a0<\/strong>\u00e0 l&rsquo;approche des comp\u00e9titions .<\/li><li>S&rsquo;\u00e9chauffer avant un effort et d\u00e9marrer progressivement .<\/li><li>Boire de l&rsquo;eau avant, pendant, et surtout apr\u00e8s l&rsquo;effort pendant 24 heures .<\/li><li>S&rsquo;alimenter correctement avant, pendant et apr\u00e8s l&rsquo;effort .<\/li><li>Mod\u00e9rer ses efforts en fonction de son entra\u00eenement, et de ses propres capacit\u00e9s .<\/li><li>La r\u00e9alisation d&rsquo;\u00e9tirements avant et surtout apr\u00e8s l\u2019effort peut att\u00e9nuer la sensation de courbatures<sup>\u00a0<\/sup>.<\/li><li>Effectuer \u00e9ventuellement le lendemain une s\u00e9ance dite de \u00ab d\u00e9crassage \u00bb, consistant g\u00e9n\u00e9ralement \u00e0 pratiquer un entra\u00eenement l\u00e9ger visant \u00e0 favoriser l\u2019\u00e9vacuation des toxines accumul\u00e9es dans les muscles .<\/li><li>La chaleur favorise la r\u00e9cup\u00e9ration physique (cr\u00e8me chauffante, bain chaud&#8230;)<\/li><li>Les <strong>antalgiques\u00a0<\/strong>et les anti-inflammatoires sur avis d\u2019un m\u00e9decin peuvent \u00eatre indiqu\u00e9s .<\/li><li>Les s\u00e9ances de massages et de physioth\u00e9rapie chez votre kin\u00e9sith\u00e9rapeute sont tr\u00e8s efficaces pour lutter contre ces courbatures.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5179d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5179d9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6413ee7c\" data-id=\"6413ee7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e249c1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e249c1b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3f095ba\" data-id=\"3f095ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2caa60ad elementor-widget elementor-widget-image\" data-id=\"2caa60ad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"435\" height=\"210\" src=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-03.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-03.png 435w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-03-300x145.png 300w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" style=\"width:100%;height:48.28%;max-width:435px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-548884c4 elementor-widget__width-initial elementor-absolute elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"548884c4\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/cercle.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/cercle.png 300w, https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/cercle-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" style=\"width:100%;height:100%;max-width:300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-493a8bcc\" data-id=\"493a8bcc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3baed469 elementor-widget elementor-widget-heading\" data-id=\"3baed469\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Navigation<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ecae720 elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ecae720\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget.elementor-icon-list--layout-inline .elementor-widget-container{overflow:hidden}.elementor-widget .elementor-icon-list-items.elementor-inline-items{margin-right:-8px;margin-left:-8px}.elementor-widget .elementor-icon-list-items.elementor-inline-items .elementor-icon-list-item{margin-right:8px;margin-left:8px}.elementor-widget .elementor-icon-list-items.elementor-inline-items .elementor-icon-list-item:after{width:auto;left:auto;right:auto;position:relative;height:100%;border-top:0;border-bottom:0;border-right:0;border-left-width:1px;border-style:solid;right:-8px}.elementor-widget .elementor-icon-list-items{list-style-type:none;margin:0;padding:0}.elementor-widget .elementor-icon-list-item{margin:0;padding:0;position:relative}.elementor-widget .elementor-icon-list-item:after{position:absolute;bottom:0;width:100%}.elementor-widget .elementor-icon-list-item,.elementor-widget .elementor-icon-list-item a{display:-webkit-box;display:-ms-flexbox;display:flex;-webkit-box-align:center;-ms-flex-align:center;align-items:center;font-size:inherit}.elementor-widget .elementor-icon-list-icon+.elementor-icon-list-text{-ms-flex-item-align:center;align-self:center;padding-left:5px}.elementor-widget .elementor-icon-list-icon{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget .elementor-icon-list-icon svg{width:var(--e-icon-list-icon-size,1em);height:var(--e-icon-list-icon-size,1em)}.elementor-widget .elementor-icon-list-icon i{width:1.25em;font-size:var(--e-icon-list-icon-size)}.elementor-widget.elementor-widget-icon-list .elementor-icon-list-icon{text-align:var(--e-icon-list-icon-align)}.elementor-widget.elementor-widget-icon-list .elementor-icon-list-icon svg{margin:var(--e-icon-list-icon-margin,0 calc(var(--e-icon-list-icon-size, 1em) * .25) 0 0)}.elementor-widget.elementor-list-item-link-full_width a{width:100%}.elementor-widget.elementor-align-center .elementor-icon-list-item,.elementor-widget.elementor-align-center .elementor-icon-list-item a{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget.elementor-align-center .elementor-icon-list-item:after{margin:auto}.elementor-widget.elementor-align-center .elementor-inline-items{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget.elementor-align-left .elementor-icon-list-item,.elementor-widget.elementor-align-left .elementor-icon-list-item a{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start;text-align:left}.elementor-widget.elementor-align-left .elementor-inline-items{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start}.elementor-widget.elementor-align-right .elementor-icon-list-item,.elementor-widget.elementor-align-right .elementor-icon-list-item a{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end;text-align:right}.elementor-widget.elementor-align-right .elementor-icon-list-items{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor-widget:not(.elementor-align-right) .elementor-icon-list-item:after{left:0}.elementor-widget:not(.elementor-align-left) .elementor-icon-list-item:after{right:0}@media (max-width:1024px){.elementor-widget.elementor-tablet-align-center .elementor-icon-list-item,.elementor-widget.elementor-tablet-align-center .elementor-icon-list-item a,.elementor-widget.elementor-tablet-align-center .elementor-icon-list-items{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget.elementor-tablet-align-center .elementor-icon-list-item:after{margin:auto}.elementor-widget.elementor-tablet-align-left .elementor-icon-list-items{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start}.elementor-widget.elementor-tablet-align-left .elementor-icon-list-item,.elementor-widget.elementor-tablet-align-left .elementor-icon-list-item a{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start;text-align:left}.elementor-widget.elementor-tablet-align-right .elementor-icon-list-items{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor-widget.elementor-tablet-align-right .elementor-icon-list-item,.elementor-widget.elementor-tablet-align-right .elementor-icon-list-item a{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end;text-align:right}.elementor-widget:not(.elementor-tablet-align-right) .elementor-icon-list-item:after{left:0}.elementor-widget:not(.elementor-tablet-align-left) .elementor-icon-list-item:after{right:0}}@media (max-width:767px){.elementor-widget.elementor-mobile-align-center .elementor-icon-list-item,.elementor-widget.elementor-mobile-align-center .elementor-icon-list-item a,.elementor-widget.elementor-mobile-align-center .elementor-icon-list-items{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget.elementor-mobile-align-center .elementor-icon-list-item:after{margin:auto}.elementor-widget.elementor-mobile-align-left .elementor-icon-list-items{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start}.elementor-widget.elementor-mobile-align-left .elementor-icon-list-item,.elementor-widget.elementor-mobile-align-left .elementor-icon-list-item a{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start;text-align:left}.elementor-widget.elementor-mobile-align-right .elementor-icon-list-items{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor-widget.elementor-mobile-align-right .elementor-icon-list-item,.elementor-widget.elementor-mobile-align-right .elementor-icon-list-item a{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end;text-align:right}.elementor-widget:not(.elementor-mobile-align-right) .elementor-icon-list-item:after{left:0}.elementor-widget:not(.elementor-mobile-align-left) .elementor-icon-list-item:after{right:0}}<\/style>\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/le-centre\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le centre de soins<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/conseils\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Conseils<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/exercice-physique\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Exercice physique<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/videos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vid\u00e9os<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-274f4fe9\" data-id=\"274f4fe9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71af1970 elementor-widget elementor-widget-heading\" data-id=\"71af1970\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liens rapides<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5522cf00 elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5522cf00\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/le-mal-de-dos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le mal de dos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/larthrose\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L'arthrose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/lalimentation\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L'alimentation<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/coach-d-azur.com\/index.php\/meditation\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La m\u00e9ditation<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e3cd729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e3cd729\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22989674\" data-id=\"22989674\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3abd7c5b elementor-widget elementor-widget-text-editor\" data-id=\"3abd7c5b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.agencemurmure.com\">\u00a9 2022\u00a0 \u2022 Cr\u00e9e par Murmure Web Production<\/a><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-71761250\" data-id=\"71761250\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d66304a elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"6d66304a\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/Picture3.png\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58bba85 e-grid-align-right e-grid-align-mobile-center elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"58bba85\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.6 - 28-02-2022 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);-webkit-box-pack:var(--justify-content,center);-ms-flex-pack:var(--justify-content,center);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)));height:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:-webkit-inline-box;display:-ms-inline-flexbox;display:inline-flex;background-color:#818a91;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#818a91}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{-webkit-border-radius:10%;border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{-webkit-border-radius:50%;border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-9234ceb\" href=\"https:\/\/www.facebook.com\/gilles.marouani\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-56f3e4a\" href=\"https:\/\/www.youtube.com\/user\/Marouanigilles\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-1e5d6f4\" href=\"https:\/\/www.instagram.com\/marouani_gilles\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le centreOpen menu Les massages Les dispositifs m\u00e9dicaux Les ondes de choc Exercice physique Un ventre plat Le cardio training La course \u00e0 pied Les \u00e9tirements Les abdominaux Soin esth\u00e9tique ConseilsOpen menu L\u2019alimentation Les entorses Les tendinites L\u2019arthrose Le mal de dos Maigrir M\u00e9ditation Les courbatures Vid\u00e9os Contact Conseils Les courbatures Les\u00a0courbatures\u00a0sont des\u00a0douleurs musculaires sans&hellip; <a class=\"more-link\" href=\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/\">Poursuivre la lecture <span class=\"screen-reader-text\">Les courbatures<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-157","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les courbatures - WordPress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les courbatures - WordPress\" \/>\n<meta property=\"og:description\" content=\"Le centreOpen menu Les massages Les dispositifs m\u00e9dicaux Les ondes de choc Exercice physique Un ventre plat Le cardio training La course \u00e0 pied Les \u00e9tirements Les abdominaux Soin esth\u00e9tique ConseilsOpen menu L\u2019alimentation Les entorses Les tendinites L\u2019arthrose Le mal de dos Maigrir M\u00e9ditation Les courbatures Vid\u00e9os Contact Conseils Les courbatures Les\u00a0courbatures\u00a0sont des\u00a0douleurs musculaires sans&hellip; Poursuivre la lecture Les courbatures\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/\" \/>\n<meta property=\"og:site_name\" content=\"WordPress\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-10T13:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/coach-d-azur.com\/#website\",\"url\":\"https:\/\/coach-d-azur.com\/\",\"name\":\"WordPress\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/coach-d-azur.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png\",\"contentUrl\":\"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png\",\"width\":435,\"height\":210},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#webpage\",\"url\":\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/\",\"name\":\"Les courbatures - WordPress\",\"isPartOf\":{\"@id\":\"https:\/\/coach-d-azur.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#primaryimage\"},\"datePublished\":\"2022-02-14T15:10:49+00:00\",\"dateModified\":\"2022-03-10T13:27:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/coach-d-azur.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les courbatures\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les courbatures - WordPress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/","og_locale":"fr_FR","og_type":"article","og_title":"Les courbatures - WordPress","og_description":"Le centreOpen menu Les massages Les dispositifs m\u00e9dicaux Les ondes de choc Exercice physique Un ventre plat Le cardio training La course \u00e0 pied Les \u00e9tirements Les abdominaux Soin esth\u00e9tique ConseilsOpen menu L\u2019alimentation Les entorses Les tendinites L\u2019arthrose Le mal de dos Maigrir M\u00e9ditation Les courbatures Vid\u00e9os Contact Conseils Les courbatures Les\u00a0courbatures\u00a0sont des\u00a0douleurs musculaires sans&hellip; Poursuivre la lecture Les courbatures","og_url":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/","og_site_name":"WordPress","article_modified_time":"2022-03-10T13:27:38+00:00","og_image":[{"url":"http:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/coach-d-azur.com\/#website","url":"https:\/\/coach-d-azur.com\/","name":"WordPress","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coach-d-azur.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png","contentUrl":"https:\/\/coach-d-azur.com\/wp-content\/uploads\/2022\/02\/gilles-marouani-masseur-kinesitherapeute-logo-test-02.png","width":435,"height":210},{"@type":"WebPage","@id":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#webpage","url":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/","name":"Les courbatures - WordPress","isPartOf":{"@id":"https:\/\/coach-d-azur.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#primaryimage"},"datePublished":"2022-02-14T15:10:49+00:00","dateModified":"2022-03-10T13:27:38+00:00","breadcrumb":{"@id":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coach-d-azur.com\/index.php\/les-courbatures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coach-d-azur.com\/"},{"@type":"ListItem","position":2,"name":"Les courbatures"}]}]}},"_links":{"self":[{"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":10,"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":899,"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/pages\/157\/revisions\/899"}],"wp:attachment":[{"href":"https:\/\/coach-d-azur.com\/index.php\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}